{"id":65,"date":"2021-05-30T22:37:27","date_gmt":"2021-05-30T22:37:27","guid":{"rendered":"https:\/\/macchieurbane.org\/?p=65"},"modified":"2021-05-31T23:36:04","modified_gmt":"2021-05-31T23:36:04","slug":"memorie-via-reginaldo-giuliani","status":"publish","type":"post","link":"https:\/\/macchieurbane.org\/index.php\/2021\/05\/30\/memorie-via-reginaldo-giuliani\/","title":{"rendered":"Memorie &#8211; Via Reginaldo Giuliani"},"content":{"rendered":"\n<p>Macchie Urbane &#8211; Via Reginaldo Giuliani<\/p>\n\n\n\n<p>Radio Wombat e NextEmerson &#8211; 25 aprile 2021<br>Registrazione live durante la passeggiata di toponomastica resistente<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-embed-handler wp-block-embed-embed-handler\"><div class=\"wp-block-embed__wrapper\">\n<audio class=\"wp-audio-shortcode\" id=\"audio-65-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/archive.org\/download\/reginaldo-giuliani\/reginaldo-giuliani.mp3?_=1\" \/><a href=\"https:\/\/archive.org\/download\/reginaldo-giuliani\/reginaldo-giuliani.mp3\">https:\/\/archive.org\/download\/reginaldo-giuliani\/reginaldo-giuliani.mp3<\/a><\/audio>\n<\/div><\/figure>\n\n\n\n<p><strong><em><a href=\"https:\/\/macchieurbane.org\/index.php\/2021\/05\/30\/memorie-via-reginaldo-giuliani\/\">Reginaldo Giuliani<\/a><\/em><\/strong> fu un prete domenicano. Fin dalla prima giovinezza si contraddistinse per le posizioni fortemente reazionarie: si schier\u00f2 attivamente contro le rivolte operaie delle fabbriche a Torino, dove nacque e si form\u00f2, partecip\u00f2 alla spedizione di Fiume, fu entusiasta aderente ai Fasci di Combattimento nel 1919 e attivo promotore dello squadrismo con le Fiamme Bianche. Venne soprannominato gi\u00e0 in vita \u201cil cappellano delle camicie nere\u201d. Giuliani fu ucciso dalla resistenza locale nella battaglia di passo Uarieu durante\u00a0la Guerra\u00a0coloniale d\u2019Etiopia. In quella campagna l\u2019esercito Italiano si macchi\u00f2 di atrocit\u00e0 condannate gi\u00e0 al tempo, ma benedette da Giuliani. Il suo nome inizi\u00f2 a ritrovarsi nella toponomastica di moltissime citt\u00e0 italiane sul finire degli anni \u201830. Fu estirpato repentinamente nel dopo guerra da citt\u00e0 come Torino, in cui il ricordo del personaggio era pi\u00f9 vivido, mentre in altre, come appunto la nostra, Roma o Milano lo ritroviamo ancora oggi. Nel 2021 a Firenze non ci siamo affatto liberati del nostro orrendo passato coloniale e abbiamo ancora una strada dedicata a lui.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Macchie Urbane &#8211; Via Reginaldo Giuliani Radio Wombat e NextEmerson &#8211; 25 aprile 2021Registrazione live durante la passeggiata di toponomastica resistente Reginaldo Giuliani fu un prete domenicano. Fin dalla prima giovinezza si contraddistinse per le posizioni fortemente reazionarie: si schier\u00f2 attivamente contro le rivolte operaie delle fabbriche a Torino, dove nacque e si form\u00f2, partecip\u00f2 &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/macchieurbane.org\/index.php\/2021\/05\/30\/memorie-via-reginaldo-giuliani\/\"> <span class=\"screen-reader-text\">Memorie &#8211; Via Reginaldo Giuliani<\/span> Read More &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","footnotes":""},"categories":[1],"tags":[7,8,6,10,5,9],"class_list":["post-65","post","type-post","status-publish","format-standard","hentry","category-memorie","tag-antifascismo","tag-colonialismo","tag-firenze","tag-italiani-brava-gente","tag-reginaldo-giuliani","tag-toponomastica-resistente"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"macchieurbane","author_link":"https:\/\/macchieurbane.org\/index.php\/author\/macchieurbane\/"},"uagb_comment_info":0,"uagb_excerpt":"Macchie Urbane &#8211; Via Reginaldo Giuliani Radio Wombat e NextEmerson &#8211; 25 aprile 2021Registrazione live durante la passeggiata di toponomastica resistente Reginaldo Giuliani fu un prete domenicano. Fin dalla prima giovinezza si contraddistinse per le posizioni fortemente reazionarie: si schier\u00f2 attivamente contro le rivolte operaie delle fabbriche a Torino, dove nacque e si form\u00f2, partecip\u00f2&hellip;","_links":{"self":[{"href":"https:\/\/macchieurbane.org\/index.php\/wp-json\/wp\/v2\/posts\/65","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/macchieurbane.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/macchieurbane.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/macchieurbane.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/macchieurbane.org\/index.php\/wp-json\/wp\/v2\/comments?post=65"}],"version-history":[{"count":2,"href":"https:\/\/macchieurbane.org\/index.php\/wp-json\/wp\/v2\/posts\/65\/revisions"}],"predecessor-version":[{"id":120,"href":"https:\/\/macchieurbane.org\/index.php\/wp-json\/wp\/v2\/posts\/65\/revisions\/120"}],"wp:attachment":[{"href":"https:\/\/macchieurbane.org\/index.php\/wp-json\/wp\/v2\/media?parent=65"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/macchieurbane.org\/index.php\/wp-json\/wp\/v2\/categories?post=65"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/macchieurbane.org\/index.php\/wp-json\/wp\/v2\/tags?post=65"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}